{"id":30,"count":9,"description":"general","link":"https:\/\/sudeepsen.org\/index.php\/category\/general\/","name":"general","slug":"general","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sudeepsen.org\/index.php\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sudeepsen.org\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sudeepsen.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sudeepsen.org\/index.php\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}